{"id":6338,"date":"2026-04-01T09:40:06","date_gmt":"2026-04-01T09:40:06","guid":{"rendered":"https:\/\/adegaalmeirim.pt\/?post_type=noticias&#038;p=6338"},"modified":"2026-04-01T09:40:25","modified_gmt":"2026-04-01T09:40:25","slug":"a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82","status":"publish","type":"noticias","link":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/","title":{"rendered":"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42"},"featured_media":6339,"template":"","class_list":["post-6338","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-\ud83c\udfa8\ud83e\udd42\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-\ud83c\udfa8\ud83e\udd42\/\" \/>\n<meta property=\"og:site_name\" content=\"Adega Almeirim\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adega.almeirim\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T09:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2026\/04\/Web-EN-Tela-Adega-de-Almeirim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2050\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/\",\"url\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/\",\"name\":\"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adegaalmeirim.pt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Web-EN-Tela-Adega-de-Almeirim.jpg\",\"datePublished\":\"2026-04-01T09:40:06+00:00\",\"dateModified\":\"2026-04-01T09:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adegaalmeirim.pt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Web-EN-Tela-Adega-de-Almeirim.jpg\",\"contentUrl\":\"https:\\\/\\\/adegaalmeirim.pt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Web-EN-Tela-Adega-de-Almeirim.jpg\",\"width\":2050,\"height\":1070},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/news\\\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adegaalmeirim.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/adegaalmeirim.pt\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#website\",\"url\":\"https:\\\/\\\/adegaalmeirim.pt\\\/\",\"name\":\"Adega Almeirim\",\"description\":\"Vinhos de Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adegaalmeirim.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#organization\",\"name\":\"Adega de Almeirim\",\"url\":\"https:\\\/\\\/adegaalmeirim.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adegaalmeirim.pt\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/badgeAdegaHome.png\",\"contentUrl\":\"https:\\\/\\\/adegaalmeirim.pt\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/badgeAdegaHome.png\",\"width\":232,\"height\":232,\"caption\":\"Adega de Almeirim\"},\"image\":{\"@id\":\"https:\\\/\\\/adegaalmeirim.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adega.almeirim\",\"https:\\\/\\\/www.instagram.com\\\/adega.almeirim\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-\ud83c\udfa8\ud83e\udd42\/","og_locale":"en_US","og_type":"article","og_title":"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim","og_url":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-\ud83c\udfa8\ud83e\udd42\/","og_site_name":"Adega Almeirim","article_publisher":"https:\/\/www.facebook.com\/adega.almeirim","article_modified_time":"2026-04-01T09:40:25+00:00","og_image":[{"width":2050,"height":1070,"url":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2026\/04\/Web-EN-Tela-Adega-de-Almeirim.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/","url":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/","name":"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42 - Adega Almeirim","isPartOf":{"@id":"https:\/\/adegaalmeirim.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/#primaryimage"},"image":{"@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/#primaryimage"},"thumbnailUrl":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2026\/04\/Web-EN-Tela-Adega-de-Almeirim.jpg","datePublished":"2026-04-01T09:40:06+00:00","dateModified":"2026-04-01T09:40:25+00:00","breadcrumb":{"@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/#primaryimage","url":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2026\/04\/Web-EN-Tela-Adega-de-Almeirim.jpg","contentUrl":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2026\/04\/Web-EN-Tela-Adega-de-Almeirim.jpg","width":2050,"height":1070},{"@type":"BreadcrumbList","@id":"https:\/\/adegaalmeirim.pt\/en\/news\/a-canvas-of-flavours-for-april-%f0%9f%8e%a8%f0%9f%a5%82\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adegaalmeirim.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/adegaalmeirim.pt\/noticias\/"},{"@type":"ListItem","position":3,"name":"TELA Viognier, a canvas of flavours for April! \ud83c\udfa8\ud83e\udd42"}]},{"@type":"WebSite","@id":"https:\/\/adegaalmeirim.pt\/#website","url":"https:\/\/adegaalmeirim.pt\/","name":"Adega Almeirim","description":"Vinhos de Portugal","publisher":{"@id":"https:\/\/adegaalmeirim.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adegaalmeirim.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/adegaalmeirim.pt\/#organization","name":"Adega de Almeirim","url":"https:\/\/adegaalmeirim.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adegaalmeirim.pt\/#\/schema\/logo\/image\/","url":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2017\/08\/badgeAdegaHome.png","contentUrl":"https:\/\/adegaalmeirim.pt\/wp-content\/uploads\/2017\/08\/badgeAdegaHome.png","width":232,"height":232,"caption":"Adega de Almeirim"},"image":{"@id":"https:\/\/adegaalmeirim.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adega.almeirim","https:\/\/www.instagram.com\/adega.almeirim\/"]}]}},"_links":{"self":[{"href":"https:\/\/adegaalmeirim.pt\/en\/wp-json\/wp\/v2\/noticias\/6338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adegaalmeirim.pt\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/adegaalmeirim.pt\/en\/wp-json\/wp\/v2\/types\/noticias"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adegaalmeirim.pt\/en\/wp-json\/wp\/v2\/media\/6339"}],"wp:attachment":[{"href":"https:\/\/adegaalmeirim.pt\/en\/wp-json\/wp\/v2\/media?parent=6338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}